{"id":1305,"date":"2019-01-23T06:31:06","date_gmt":"2019-01-23T06:31:06","guid":{"rendered":"http:\/\/moica.com.ar\/index.php\/home\/"},"modified":"2025-07-07T23:51:43","modified_gmt":"2025-07-07T23:51:43","slug":"pretales","status":"publish","type":"page","link":"https:\/\/www.moicca.com.ar\/","title":{"rendered":"Inicio"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"1305\" class=\"elementor elementor-1305\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ad9819e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ad9819e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-24776a7\" data-id=\"24776a7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ca48ff1 elementor-arrows-position-inside elementor-invisible elementor-widget elementor-widget-image-carousel\" data-id=\"ca48ff1\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;3&quot;,&quot;slides_to_scroll&quot;:&quot;1&quot;,&quot;autoplay_speed&quot;:2000,&quot;speed&quot;:2500,&quot;navigation&quot;:&quot;arrows&quot;,&quot;image_spacing_custom&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:30,&quot;sizes&quot;:[]},&quot;pause_on_hover&quot;:&quot;no&quot;,&quot;pause_on_interaction&quot;:&quot;no&quot;,&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;infinite&quot;:&quot;yes&quot;,&quot;image_spacing_custom_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carrusel de im\u00e1genes\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 de 2\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ca48ff1\" data-elementor-lightbox-title=\"Cuotas sin interes\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MzkyMiwidXJsIjoiaHR0cHM6XC9cL3d3dy5tb2ljY2EuY29tLmFyXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI1XC8wM1wvQXJuZXNlcy1Db21vZG9zLXktc2VndXJvcy0xLnBuZyIsInNsaWRlc2hvdyI6ImNhNDhmZjEifQ%3D%3D\" href=\"https:\/\/www.moicca.com.ar\/index.php\/tienda\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.moicca.com.ar\/wp-content\/uploads\/2025\/03\/Arneses-Comodos-y-seguros-1.png\" alt=\"cuotas-sin-interes\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 de 2\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ca48ff1\" data-elementor-lightbox-title=\"3(8)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MzgzMSwidXJsIjoiaHR0cHM6XC9cL3d3dy5tb2ljY2EuY29tLmFyXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI1XC8wMlwvMzgucG5nIiwic2xpZGVzaG93IjoiY2E0OGZmMSJ9\" href=\"https:\/\/www.moicca.com.ar\/index.php\/tienda\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.moicca.com.ar\/wp-content\/uploads\/2025\/02\/38-768x402.png\" alt=\"10-off\" \/><\/figure><\/a><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-arrow-alt-circle-left\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-arrow-alt-circle-right\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d25b445 elementor-align-center animated-fast elementor-widget elementor-widget-button\" data-id=\"d25b445\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-buzz-out\" href=\"https:\/\/www.moicca.com.ar\/index.php\/tienda\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">COMPRAR AHORA<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5370a06 elementor-section-height-min-height elementor-section-items-bottom elementor-section-content-top elementor-section-boxed elementor-section-height-default\" data-id=\"5370a06\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-e38d65f\" data-id=\"e38d65f\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a290caa elementor-invisible elementor-widget elementor-widget-image-box\" data-id=\"a290caa\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><div class=\"elementor-image-box-content\"><h4 class=\"elementor-image-box-title\"><br><br><br><br>ARN\u00c9S MARIPOSAS<\/h4><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-88209b9 elementor-align-center elementor-invisible elementor-widget elementor-widget-button\" data-id=\"88209b9\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xs\" href=\"https:\/\/www.moicca.com.ar\/index.php\/producto\/pretal-mariposas\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Ver en la tienda<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-0b6e081\" data-id=\"0b6e081\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5d64031 elementor-invisible elementor-widget elementor-widget-image-box\" data-id=\"5d64031\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><div class=\"elementor-image-box-content\"><h4 class=\"elementor-image-box-title\"><br><br><br><br>ARN\u00c9S CAMUFLADO ROSA<\/h4><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2363cee elementor-align-center elementor-invisible elementor-widget elementor-widget-button\" data-id=\"2363cee\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xs\" href=\"https:\/\/www.moicca.com.ar\/index.php\/producto\/pretal-camuflado-rosa\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Ver en la tienda<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-ea00e29\" data-id=\"ea00e29\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a1791a0 elementor-invisible elementor-widget elementor-widget-image-box\" data-id=\"a1791a0\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><div class=\"elementor-image-box-content\"><h4 class=\"elementor-image-box-title\"><br><br><br><br>ARN\u00c9S ANIMAL PRINT<\/h4><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c119a31 elementor-align-center elementor-invisible elementor-widget elementor-widget-button\" data-id=\"c119a31\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xs\" href=\"https:\/\/www.moicca.com.ar\/index.php\/producto\/pretal-animal-print\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Ver en la tienda<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-979769c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"979769c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1eb4aa3\" data-id=\"1eb4aa3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7df39fe elementor-widget elementor-widget-heading\" data-id=\"7df39fe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">CINTURONES DE SEGURIDAD<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9f7e6f2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9f7e6f2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-3fb02ea\" data-id=\"3fb02ea\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4a76d28 elementor-widget elementor-widget-image\" data-id=\"4a76d28\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.moicca.com.ar\/index.php\/producto\/cinturon-de-seguridad-mujer-maravilla\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.moicca.com.ar\/wp-content\/uploads\/elementor\/thumbs\/1000265198-scaled-r33zutntkstu1cezxr9vyoa3gadk4pc57nqkqpdf3s.jpg\" title=\"Cinturon Mariposas\" alt=\"cinturon-mariposas\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2b71b3c elementor-widget elementor-widget-heading\" data-id=\"2b71b3c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-medium\">MARIPOSAS<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6763264 elementor-align-center elementor-invisible elementor-widget elementor-widget-button\" data-id=\"6763264\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xs\" href=\"https:\/\/www.moicca.com.ar\/index.php\/producto\/cinturon-mariposas\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">A\u00f1adir al carrito<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-06e0ef4\" data-id=\"06e0ef4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2ea9355 elementor-widget elementor-widget-image\" data-id=\"2ea9355\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.moicca.com.ar\/index.php\/producto\/cinturon-de-seguridad-batman\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.moicca.com.ar\/wp-content\/uploads\/elementor\/thumbs\/1000265197-scaled-r33ztoax8397ui32n9eawyptbc1eq0rydz17mj2qpk.jpg\" title=\"Cinturon Camuflado Rosa\" alt=\"cinturon-camuflado-rosa\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d7bdfbd elementor-widget elementor-widget-heading\" data-id=\"d7bdfbd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-medium\">CAMUFLADO ROSA<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0a6a340 elementor-align-center elementor-invisible elementor-widget elementor-widget-button\" data-id=\"0a6a340\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xs\" href=\"https:\/\/www.moicca.com.ar\/index.php\/producto\/cinturon-camuflado-rosa\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">A\u00f1adir al carrito<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-ff27298\" data-id=\"ff27298\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4df5fba elementor-widget elementor-widget-image\" data-id=\"4df5fba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.moicca.com.ar\/index.php\/producto\/cinturon-de-seguridad-superman\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.moicca.com.ar\/wp-content\/uploads\/elementor\/thumbs\/1000265429-scaled-r3404k9me05sbw9q2gtqapt110dgvt00vv2oqwxkmw.jpg\" title=\"Cinturon Animal Print\" alt=\"cinturon-animal-print\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-262833c elementor-widget elementor-widget-heading\" data-id=\"262833c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-medium\">ANIMAL PRINT<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e146592 elementor-align-center elementor-invisible elementor-widget elementor-widget-button\" data-id=\"e146592\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xs\" href=\"https:\/\/www.moicca.com.ar\/index.php\/producto\/cinturon-animal-print\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">A\u00f1adir al carrito<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3d36450 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3d36450\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-3999eb5\" data-id=\"3999eb5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d38a3da elementor-view-stacked elementor-position-inline-start elementor-widget__width-auto elementor-shape-circle elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"d38a3da\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-shipping-fast\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h5 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tENVIOS A DOMICILIO\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tHacemos env\u00edos a todo el pa\u00eds.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-b37c16b\" data-id=\"b37c16b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ac1caf9 elementor-view-stacked elementor-position-inline-start elementor-widget__width-auto elementor-shape-circle elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"ac1caf9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-credit-card\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h5 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tMEDIOS DE PAGO\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tAceptamos efectivo, transferencia, tarjeta de cr\u00e9dito\/d\u00e9bito y mercado pago! \t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-67214ef\" data-id=\"67214ef\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d1af5a3 elementor-view-stacked elementor-position-inline-start elementor-widget__width-auto elementor-shape-circle elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"d1af5a3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"https:\/\/www.instagram.com\/moicca.mascotas\/\" class=\"elementor-icon\" tabindex=\"-1\" aria-label=\"SEGUINOS EN INSTAGRAM\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-instagram\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h5 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.instagram.com\/moicca.mascotas\/\" >\n\t\t\t\t\t\t\tSEGUINOS EN INSTAGRAM\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tPara ver los nuevos ingresos, revis\u00e1 nuestras redes sociales.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6d3c02f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6d3c02f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-56afb86\" data-id=\"56afb86\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4e06c1e elementor-widget elementor-widget-html\" data-id=\"4e06c1e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div style=\r\n\"overflow: hidden; \r\nbackground-color: #000;\r\ncolor: #fff;\r\nfont-size: 20px;\r\nfont-weight: bold;\r\nalign-items: center;\r\n\r\n\">\r\n<marquee \r\ndirection=\"left\" \r\nbehavior=\"scroll\" \r\nscrollamount=\"10\" \r\nstyle=\"white-space: nowrap;\r\npadding: 5px;\r\n\">\r\n\u00a1OFERTAS MOICCA! HASTA 40% OFF \u00a1OFERTAS MOICCA! HASTA 40% OFF \u00a1OFERTAS MOICCA! HASTA 40% OFF \u00a1OFERTAS MOICCA! HASTA 40% OFF \u00a1OFERTAS MOICCA! HASTA 40% OFF \u00a1OFERTAS MOICCA! HASTA 40% OFF\r\n<\/marquee>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9632002 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9632002\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f9a8047\" data-id=\"f9a8047\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-69db4ba elementor-widget elementor-widget-html\" data-id=\"69db4ba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<html>\r\n<head>\r\n    <title>Slider Autom\u00e1tico con Grupos de 3 Im\u00e1genes<\/title>\r\n    <style>\r\n\r\n        .slider-container {\r\n            display: flex;\r\n            overflow: hidden;\r\n            width: 100%;\r\n            margin: 0 auto;\r\n        }\r\n\r\n        .slider {\r\n            display: flex;\r\n            width: 300%;\r\n            animation: slide 15s 2s infinite;\r\n        }\r\n\r\n        .slider-item {\r\n            flex: 0 0 33.33%;\r\n            text-align: center;\r\n        }\r\n\r\n        .slider-item img {\r\n            width: 50%;\r\n            margin-bottom: 10px;\r\n        }\r\n\r\n        \/* Animaci\u00f3n del slider *\/\r\n        @keyframes slide {\r\n            0% { transform: translateX(0); }\r\n            33.33% { transform: translateX(-100%); }\r\n            66.66% { transform: translateX(-200%); }\r\n            100% { transform: translateX(0); }\r\n        }\r\n    <\/style>\r\n<\/head>\r\n<body>\r\n    <div class=\"slider-container\">\r\n        <div class=\"slider\">\r\n            <!-- Grupo 1 -->\r\n            <div class=\"slider-item\">\r\n            <img decoding=\"async\" src=\"https:\/\/www.moicca.com.ar\/wp-content\/uploads\/2022\/07\/Picsart_25-03-14_19-08-52-693-scaled.jpg\">\r\n            <p>Pretal Azul<\/p>\r\n            <\/div>\r\n            <div class=\"slider-item\">\r\n            <img decoding=\"async\" src=\"https:\/\/www.moicca.com.ar\/wp-content\/uploads\/2023\/08\/PicsArt_07-27-01.21.16-scaled-1-jpg.webp\">\r\n            <p>Pretal Smoking<\/p>\r\n            <\/div>\r\n            <div class=\"slider-item\">\r\n            <img decoding=\"async\" src=\"https:\/\/www.moicca.com.ar\/wp-content\/uploads\/2021\/10\/Picsart_25-03-14_19-00-25-830-scaled.jpg\">\r\n            <p>Pretal Negro<\/p>\r\n            <\/div>\r\n\r\n            <!-- Grupo 2 -->\r\n            <div class=\"slider-item\">\r\n            <img decoding=\"async\" src=\"https:\/\/www.moicca.com.ar\/wp-content\/uploads\/2022\/06\/Picsart_25-03-14_18-49-57-534-scaled.jpg\" alt=\"Pretal-Violeta\">\r\n            <p>Pretal Negro con Rojo<\/p>\r\n            <\/div>\r\n            <div class=\"slider-item\">\r\n            <img decoding=\"async\" src=\"https:\/\/www.moicca.com.ar\/wp-content\/uploads\/2023\/08\/Picsart_25-03-13_17-09-57-384-scaled.jpg\">\r\n            <p>Colchoneta Roja <\/p>\r\n            <\/div>\r\n            <div class=\"slider-item\">\r\n            <img decoding=\"async\" src=\"https:\/\/www.moicca.com.ar\/wp-content\/uploads\/2023\/08\/Picsart_25-03-13_17-15-18-762-scaled.jpg\">\r\n            <p>Colchoneta Gris<\/p>\r\n            <\/div>\r\n\r\n            <!-- Grupo 3 -->\r\n            <div class=\"slider-item\">\r\n            <img decoding=\"async\" src=\"https:\/\/www.moicca.com.ar\/wp-content\/uploads\/2021\/11\/Picsart_25-03-14_11-57-31-199-scaled.jpg\" alt=\"Colchoneta-Rayada\">\r\n            <p>Colchoneta Rayada<\/p>\r\n            <\/div>\r\n            <div class=\"slider-item\">\r\n            <img decoding=\"async\" src=\"https:\/\/www.moicca.com.ar\/wp-content\/uploads\/2021\/11\/Picsart_23-07-31_15-07-13-633-scaled.webp\" alt=\"Colchoneta-Celeste\">\r\n            <p>Colchoneta Celeste<\/p>\r\n            <\/div>\r\n            <div class=\"slider-item\">\r\n            <img decoding=\"async\" src=\"https:\/\/www.moicca.com.ar\/wp-content\/uploads\/2021\/11\/Picsart_23-07-31_15-26-11-588-scaled.webp\" alt=\"Colchoneta-Roja\">\r\n            <p>Colchoneta Roja con detalles blancos<\/p>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/body>\r\n<\/html>\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6a5a995 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6a5a995\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9bcc3d2\" data-id=\"9bcc3d2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1fbf889 elementor-button-danger elementor-align-center elementor-widget elementor-widget-button\" data-id=\"1fbf889\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.moicca.com.ar\/index.php\/categoria-producto\/ofertas\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">VER OFERTAS<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-283033f elementor-widget elementor-widget-spacer\" data-id=\"283033f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-eca0316 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"eca0316\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6d0ba37\" data-id=\"6d0ba37\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0a9524b elementor-widget elementor-widget-text-editor\" data-id=\"0a9524b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Somos\u00a0<a href=\"https:\/\/www.instagram.com\/moicca.mascotas\/?hl=es\" target=\"_blank\" rel=\"noopener\">Moicca Mascotas<\/a>, fabricantes y distribuidores de pretales, correas y colchonetas para que tu mascota pueda disfrutar su paseo diario y tambi\u00e9n su merecido descanso. Como sabemos que es parte de tu familia, dise\u00f1amos los productos con mucho amor y calidad, para ellos que se lo merecen.<\/p><p>Nuestra tienda online tiene un dise\u00f1o simple y amigable, para que puedas aprovechar y organizar tu compra de la mejor manera. Fabricamos los pretales con un material ideal para tu mascota (Soft Neoprene), as\u00ed no sufre el calor ni el fr\u00edo, se adapta a su cuerpo y contamos con una gran variedad de talles.<\/p><p>\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>COMPRAR AHORA ARN\u00c9S MARIPOSAS Ver en la tienda ARN\u00c9S CAMUFLADO ROSA Ver en la tienda ARN\u00c9S ANIMAL PRINT Ver en la tienda CINTURONES DE SEGURIDAD MARIPOSAS A\u00f1adir al carrito CAMUFLADO ROSA A\u00f1adir al carrito ANIMAL PRINT A\u00f1adir al carrito ENVIOS A DOMICILIO Hacemos env\u00edos a todo el pa\u00eds. MEDIOS DE PAGO Aceptamos efectivo, transferencia, tarjeta [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"disabled","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-1305","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Moicca Mascotas - La tienda de tu mascota! Pretales, correas y mas<\/title>\n<meta name=\"description\" content=\"Pretales ideales para tu mascota! Tenemos muchos dise\u00f1os! Hac\u00e9 tu pedido, pagalo online y recibilo en tu domicilio o retiralo!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.moicca.com.ar\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Moicca Mascotas - La tienda de tu mascota! Pretales, correas y mas\" \/>\n<meta property=\"og:description\" content=\"Pretales ideales para tu mascota! Tenemos muchos dise\u00f1os! Hac\u00e9 tu pedido, pagalo online y recibilo en tu domicilio o retiralo!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.moicca.com.ar\/\" \/>\n<meta property=\"og:site_name\" content=\"Moicca Mascotas\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-07T23:51:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.moicca.com.ar\/wp-content\/uploads\/2025\/03\/Arneses-Comodos-y-seguros-1.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.moicca.com.ar\\\/\",\"url\":\"https:\\\/\\\/www.moicca.com.ar\\\/\",\"name\":\"Moicca Mascotas - La tienda de tu mascota! Pretales, correas y mas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.moicca.com.ar\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.moicca.com.ar\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.moicca.com.ar\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.moicca.com.ar\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Arneses-Comodos-y-seguros-1.png\",\"datePublished\":\"2019-01-23T06:31:06+00:00\",\"dateModified\":\"2025-07-07T23:51:43+00:00\",\"description\":\"Pretales ideales para tu mascota! Tenemos muchos dise\u00f1os! Hac\u00e9 tu pedido, pagalo online y recibilo en tu domicilio o retiralo!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.moicca.com.ar\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.moicca.com.ar\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.moicca.com.ar\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.moicca.com.ar\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Arneses-Comodos-y-seguros-1.png\",\"contentUrl\":\"https:\\\/\\\/www.moicca.com.ar\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Arneses-Comodos-y-seguros-1.png\",\"width\":575,\"height\":301,\"caption\":\"cuotas-sin-interes\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.moicca.com.ar\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.moicca.com.ar\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Inicio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.moicca.com.ar\\\/#website\",\"url\":\"https:\\\/\\\/www.moicca.com.ar\\\/\",\"name\":\"Moicca Mascotas\",\"description\":\"Accesorios para mascotas\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.moicca.com.ar\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.moicca.com.ar\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.moicca.com.ar\\\/#organization\",\"name\":\"Moicca Mascotas\",\"url\":\"https:\\\/\\\/www.moicca.com.ar\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.moicca.com.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.moicca.com.ar\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/cropped-Picsart_23-07-22_14-00-20-313-1-scaled-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.moicca.com.ar\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/cropped-Picsart_23-07-22_14-00-20-313-1-scaled-1.jpg\",\"width\":512,\"height\":512,\"caption\":\"Moicca Mascotas\"},\"image\":{\"@id\":\"https:\\\/\\\/www.moicca.com.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/moicca.mascotas\\\/?hl=es\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Moicca Mascotas - La tienda de tu mascota! Pretales, correas y mas","description":"Pretales ideales para tu mascota! Tenemos muchos dise\u00f1os! Hac\u00e9 tu pedido, pagalo online y recibilo en tu domicilio o retiralo!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.moicca.com.ar\/","og_locale":"es_ES","og_type":"article","og_title":"Moicca Mascotas - La tienda de tu mascota! Pretales, correas y mas","og_description":"Pretales ideales para tu mascota! Tenemos muchos dise\u00f1os! Hac\u00e9 tu pedido, pagalo online y recibilo en tu domicilio o retiralo!","og_url":"https:\/\/www.moicca.com.ar\/","og_site_name":"Moicca Mascotas","article_modified_time":"2025-07-07T23:51:43+00:00","og_image":[{"url":"https:\/\/www.moicca.com.ar\/wp-content\/uploads\/2025\/03\/Arneses-Comodos-y-seguros-1.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.moicca.com.ar\/","url":"https:\/\/www.moicca.com.ar\/","name":"Moicca Mascotas - La tienda de tu mascota! Pretales, correas y mas","isPartOf":{"@id":"https:\/\/www.moicca.com.ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.moicca.com.ar\/#primaryimage"},"image":{"@id":"https:\/\/www.moicca.com.ar\/#primaryimage"},"thumbnailUrl":"https:\/\/www.moicca.com.ar\/wp-content\/uploads\/2025\/03\/Arneses-Comodos-y-seguros-1.png","datePublished":"2019-01-23T06:31:06+00:00","dateModified":"2025-07-07T23:51:43+00:00","description":"Pretales ideales para tu mascota! Tenemos muchos dise\u00f1os! Hac\u00e9 tu pedido, pagalo online y recibilo en tu domicilio o retiralo!","breadcrumb":{"@id":"https:\/\/www.moicca.com.ar\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.moicca.com.ar\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.moicca.com.ar\/#primaryimage","url":"https:\/\/www.moicca.com.ar\/wp-content\/uploads\/2025\/03\/Arneses-Comodos-y-seguros-1.png","contentUrl":"https:\/\/www.moicca.com.ar\/wp-content\/uploads\/2025\/03\/Arneses-Comodos-y-seguros-1.png","width":575,"height":301,"caption":"cuotas-sin-interes"},{"@type":"BreadcrumbList","@id":"https:\/\/www.moicca.com.ar\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.moicca.com.ar\/"},{"@type":"ListItem","position":2,"name":"Inicio"}]},{"@type":"WebSite","@id":"https:\/\/www.moicca.com.ar\/#website","url":"https:\/\/www.moicca.com.ar\/","name":"Moicca Mascotas","description":"Accesorios para mascotas","publisher":{"@id":"https:\/\/www.moicca.com.ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.moicca.com.ar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.moicca.com.ar\/#organization","name":"Moicca Mascotas","url":"https:\/\/www.moicca.com.ar\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.moicca.com.ar\/#\/schema\/logo\/image\/","url":"https:\/\/www.moicca.com.ar\/wp-content\/uploads\/2023\/07\/cropped-Picsart_23-07-22_14-00-20-313-1-scaled-1.jpg","contentUrl":"https:\/\/www.moicca.com.ar\/wp-content\/uploads\/2023\/07\/cropped-Picsart_23-07-22_14-00-20-313-1-scaled-1.jpg","width":512,"height":512,"caption":"Moicca Mascotas"},"image":{"@id":"https:\/\/www.moicca.com.ar\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/moicca.mascotas\/?hl=es"]}]}},"_links":{"self":[{"href":"https:\/\/www.moicca.com.ar\/index.php\/wp-json\/wp\/v2\/pages\/1305","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.moicca.com.ar\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.moicca.com.ar\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.moicca.com.ar\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.moicca.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=1305"}],"version-history":[{"count":561,"href":"https:\/\/www.moicca.com.ar\/index.php\/wp-json\/wp\/v2\/pages\/1305\/revisions"}],"predecessor-version":[{"id":4002,"href":"https:\/\/www.moicca.com.ar\/index.php\/wp-json\/wp\/v2\/pages\/1305\/revisions\/4002"}],"wp:attachment":[{"href":"https:\/\/www.moicca.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=1305"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}